{"id":12,"count":2,"description":"","link":"https:\/\/2blog.ilc.edu.tw\/englishvillage\/category\/113%e5%ad%b8%e5%b9%b4%e5%ba%a6\/","name":"113\u5b78\u5e74\u5ea6","slug":"113%e5%ad%b8%e5%b9%b4%e5%ba%a6","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/2blog.ilc.edu.tw\/englishvillage\/wp-json\/wp\/v2\/categories\/12"}],"collection":[{"href":"https:\/\/2blog.ilc.edu.tw\/englishvillage\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/2blog.ilc.edu.tw\/englishvillage\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/2blog.ilc.edu.tw\/englishvillage\/wp-json\/wp\/v2\/posts?categories=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}